{"id":1554,"count":3,"description":"","link":"https:\/\/observatoireprevention.org\/en\/topics\/nutrition-en\/fat\/omega-3_en\/","name":"Omega-3","slug":"omega-3_en","taxonomy":"category","parent":1552,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dossier Omega-3 | Prevention Observatory of the Montreal Heart Institute<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/observatoireprevention.org\/en\/topics\/nutrition-en\/fat\/omega-3_en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dossier Omega-3 | Prevention Observatory of the Montreal Heart Institute\" \/>\n<meta property=\"og:url\" content=\"https:\/\/observatoireprevention.org\/en\/topics\/nutrition-en\/fat\/omega-3_en\/\" \/>\n<meta property=\"og:site_name\" content=\"Prevention Observatory of the Montreal Heart Institute\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PreventionICM\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/topics\\\/nutrition-en\\\/fat\\\/omega-3_en\\\/\",\"url\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/topics\\\/nutrition-en\\\/fat\\\/omega-3_en\\\/\",\"name\":\"Dossier Omega-3 | Prevention Observatory of the Montreal Heart Institute\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/topics\\\/nutrition-en\\\/fat\\\/omega-3_en\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/topics\\\/nutrition-en\\\/fat\\\/omega-3_en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nutrition\",\"item\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/topics\\\/nutrition-en\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fat\",\"item\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/topics\\\/nutrition-en\\\/fat\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Omega-3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/\",\"name\":\"Observatoire de la pr\u00e9vention de l'Institut de Cardiologie de Montr\u00e9al\",\"description\":\"Promote the prevention of cardiovascular diseases to extend healthy life expectancy.\",\"publisher\":{\"@id\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/#organization\",\"name\":\"Prevention Observatory of the Montreal Heart Institute\",\"url\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/observatoireprevention.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-admin.png\",\"contentUrl\":\"https:\\\/\\\/observatoireprevention.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-admin.png\",\"width\":500,\"height\":69,\"caption\":\"Prevention Observatory of the Montreal Heart Institute\"},\"image\":{\"@id\":\"https:\\\/\\\/observatoireprevention.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/drjuneau\\\/\",\"https:\\\/\\\/x.com\\\/PreventionICM\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/observatoire-de-la-prvention-de-linstitut-de-cardiologie-de-montral\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dossier Omega-3 | Prevention Observatory of the Montreal Heart Institute","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/observatoireprevention.org\/en\/topics\/nutrition-en\/fat\/omega-3_en\/","og_locale":"en_US","og_type":"article","og_title":"Dossier Omega-3 | Prevention Observatory of the Montreal Heart Institute","og_url":"https:\/\/observatoireprevention.org\/en\/topics\/nutrition-en\/fat\/omega-3_en\/","og_site_name":"Prevention Observatory of the Montreal Heart Institute","twitter_card":"summary_large_image","twitter_site":"@PreventionICM","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/observatoireprevention.org\/en\/topics\/nutrition-en\/fat\/omega-3_en\/","url":"https:\/\/observatoireprevention.org\/en\/topics\/nutrition-en\/fat\/omega-3_en\/","name":"Dossier Omega-3 | Prevention Observatory of the Montreal Heart Institute","isPartOf":{"@id":"https:\/\/observatoireprevention.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/observatoireprevention.org\/en\/topics\/nutrition-en\/fat\/omega-3_en\/#breadcrumb"},"inLanguage":"en-CA"},{"@type":"BreadcrumbList","@id":"https:\/\/observatoireprevention.org\/en\/topics\/nutrition-en\/fat\/omega-3_en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/observatoireprevention.org\/en\/"},{"@type":"ListItem","position":2,"name":"Nutrition","item":"https:\/\/observatoireprevention.org\/en\/topics\/nutrition-en\/"},{"@type":"ListItem","position":3,"name":"Fat","item":"https:\/\/observatoireprevention.org\/en\/topics\/nutrition-en\/fat\/"},{"@type":"ListItem","position":4,"name":"Omega-3"}]},{"@type":"WebSite","@id":"https:\/\/observatoireprevention.org\/en\/#website","url":"https:\/\/observatoireprevention.org\/en\/","name":"Observatoire de la pr\u00e9vention de l'Institut de Cardiologie de Montr\u00e9al","description":"Promote the prevention of cardiovascular diseases to extend healthy life expectancy.","publisher":{"@id":"https:\/\/observatoireprevention.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/observatoireprevention.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/observatoireprevention.org\/en\/#organization","name":"Prevention Observatory of the Montreal Heart Institute","url":"https:\/\/observatoireprevention.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/observatoireprevention.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/observatoireprevention.org\/wp-content\/uploads\/2026\/04\/logo-admin.png","contentUrl":"https:\/\/observatoireprevention.org\/wp-content\/uploads\/2026\/04\/logo-admin.png","width":500,"height":69,"caption":"Prevention Observatory of the Montreal Heart Institute"},"image":{"@id":"https:\/\/observatoireprevention.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/drjuneau\/","https:\/\/x.com\/PreventionICM","https:\/\/www.linkedin.com\/company\/observatoire-de-la-prvention-de-linstitut-de-cardiologie-de-montral\/"]}]}},"_links":{"self":[{"href":"https:\/\/observatoireprevention.org\/en\/wp-json\/wp\/v2\/categories\/1554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/observatoireprevention.org\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/observatoireprevention.org\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/observatoireprevention.org\/en\/wp-json\/wp\/v2\/categories\/1552"}],"wp:post_type":[{"href":"https:\/\/observatoireprevention.org\/en\/wp-json\/wp\/v2\/posts?categories=1554"},{"href":"https:\/\/observatoireprevention.org\/en\/wp-json\/wp\/v2\/media?categories=1554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}